{"id":4212,"date":"2021-11-30T15:09:07","date_gmt":"2021-11-30T18:09:07","guid":{"rendered":"https:\/\/saude.ufpr.br\/terapiaocupacional\/?page_id=4212"},"modified":"2022-04-29T13:17:59","modified_gmt":"2022-04-29T16:17:59","slug":"paloma-hohmann-poier","status":"publish","type":"page","link":"https:\/\/saude.ufpr.br\/terapiaocupacional\/paloma-hohmann-poier\/","title":{"rendered":"Paloma Hohmann Poier"},"content":{"rendered":"<p>Docente no departamento de Terapia Ocupacional da UFPR. Doutora em Engenharia Mec\u00e2nica e de Materiais (PPGEM) e Mestre em Engenharia Biom\u00e9dica pela Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR). Terapeuta Ocupacional pela Universidade Federal do Paran\u00e1 (UFPR). Atuou como terapeuta ocupacional nas \u00e1reas de Psiquiatria, Geriatria e Gerontologia, Neuropediatria e em contextos social e escolar. Desenvolveu consultoria especializada para o Programa das Na\u00e7\u00f5es Unidas e Desenvolvimento (PNUD) em pesquisa sobre as condi\u00e7\u00f5es de inclus\u00e3o das Pessoas com Defici\u00eancia \u00e0 Educa\u00e7\u00e3o Profissional. Integrante da &#8220;Rede de Pesquisa e Desenvolvimento em Tecnologia Assistiva: a\u00e7\u00f5es integradas entre Engenharia Mec\u00e2nica e Design&#8221;. Desenvolve pesquisas e a\u00e7\u00f5es de extens\u00e3o na \u00e1rea de Tecnologia Assistiva, Tecnologias de Reabilita\u00e7\u00e3o e trabalho\/pesquisa interprofissional.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Docente no departamento de Terapia Ocupacional da UFPR. Doutora em Engenharia Mec\u00e2nica e de Materiais (PPGEM) e Mestre em Engenharia Biom\u00e9dica pela Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR). Terapeuta Ocupacional pela Universidade Federal do Paran\u00e1 (UFPR). Atuou como terapeuta ocupacional [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-4212","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"caiubidysarz","author_link":"https:\/\/saude.ufpr.br\/terapiaocupacional\/author\/caiubidysarz\/"},"uagb_comment_info":0,"uagb_excerpt":"Docente no departamento de Terapia Ocupacional da UFPR. Doutora em Engenharia Mec\u00e2nica e de Materiais (PPGEM) e Mestre em Engenharia Biom\u00e9dica pela Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR). Terapeuta Ocupacional pela Universidade Federal do Paran\u00e1 (UFPR). Atuou como terapeuta ocupacional [&hellip;]","publishpress_future_action":{"enabled":false,"date":"2026-07-22 00:47:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/pages\/4212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/comments?post=4212"}],"version-history":[{"count":2,"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/pages\/4212\/revisions"}],"predecessor-version":[{"id":4285,"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/pages\/4212\/revisions\/4285"}],"wp:attachment":[{"href":"https:\/\/saude.ufpr.br\/terapiaocupacional\/wp-json\/wp\/v2\/media?parent=4212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}